{"id":22,"count":1,"description":"","link":"https:\/\/wavetrap.com\/en\/tag\/impact\/","name":"Impact","slug":"impact","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Impact Archives - WaveTrap<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Impact Archives - WaveTrap\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wavetrap.com\/en\/tag\/impact\/\" \/>\n<meta property=\"og:site_name\" content=\"WaveTrap\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/wavetrap.com\\\/en\\\/tag\\\/impact\\\/\",\"url\":\"https:\\\/\\\/wavetrap.com\\\/en\\\/tag\\\/impact\\\/\",\"name\":\"Impact Archives - WaveTrap\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wavetrap.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/wavetrap.com\\\/en\\\/tag\\\/impact\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/wavetrap.com\\\/en\\\/tag\\\/impact\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/wavetrap.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Impact\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wavetrap.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/wavetrap.com\\\/en\\\/\",\"name\":\"WaveTrap\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/wavetrap.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wavetrap.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/wavetrap.com\\\/en\\\/#organization\",\"name\":\"WaveTrap\",\"url\":\"https:\\\/\\\/wavetrap.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/wavetrap.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/wavetrap.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/wavetrap-logo-color.svg\",\"contentUrl\":\"https:\\\/\\\/wavetrap.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/wavetrap-logo-color.svg\",\"width\":534,\"height\":104,\"caption\":\"WaveTrap\"},\"image\":{\"@id\":\"https:\\\/\\\/wavetrap.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Impact Archives - WaveTrap","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"Impact Archives - WaveTrap","og_url":"https:\/\/wavetrap.com\/en\/tag\/impact\/","og_site_name":"WaveTrap","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/wavetrap.com\/en\/tag\/impact\/","url":"https:\/\/wavetrap.com\/en\/tag\/impact\/","name":"Impact Archives - WaveTrap","isPartOf":{"@id":"https:\/\/wavetrap.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/wavetrap.com\/en\/tag\/impact\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/wavetrap.com\/en\/tag\/impact\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/wavetrap.com\/en\/"},{"@type":"ListItem","position":2,"name":"Impact"}]},{"@type":"WebSite","@id":"https:\/\/wavetrap.com\/en\/#website","url":"https:\/\/wavetrap.com\/en\/","name":"WaveTrap","description":"","publisher":{"@id":"https:\/\/wavetrap.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wavetrap.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/wavetrap.com\/en\/#organization","name":"WaveTrap","url":"https:\/\/wavetrap.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/wavetrap.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/wavetrap.com\/wp-content\/uploads\/2026\/06\/wavetrap-logo-color.svg","contentUrl":"https:\/\/wavetrap.com\/wp-content\/uploads\/2026\/06\/wavetrap-logo-color.svg","width":534,"height":104,"caption":"WaveTrap"},"image":{"@id":"https:\/\/wavetrap.com\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/wavetrap.com\/en\/wp-json\/wp\/v2\/tags\/22","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wavetrap.com\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/wavetrap.com\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/wavetrap.com\/en\/wp-json\/wp\/v2\/posts?tags=22"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}